{"id":7926,"date":"2021-01-18T16:40:19","date_gmt":"2021-01-18T15:40:19","guid":{"rendered":"https:\/\/www.chateaunantes.fr\/?page_id=7926"},"modified":"2026-07-08T12:34:33","modified_gmt":"2026-07-08T10:34:33","slug":"sellos","status":"publish","type":"page","link":"https:\/\/www.chateaunantes.fr\/es\/el-castillo\/sellos\/","title":{"rendered":"Sellos"},"content":{"rendered":"\n<p>La atenci\u00f3n al p\u00fablico es primordial en el proyecto del castillo, comprometido con procedimientos de calidad y obtenci\u00f3n de certificaciones.<\/p>\n\n\n\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile is-vertically-aligned-top\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/www.chateaunantes.fr\/wp-content\/uploads\/2020\/03\/qualitetourisme-1.png\" alt=\"Logo Qualit\u00e9 Tourisme\" class=\"wp-image-343 size-full\" srcset=\"https:\/\/www.chateaunantes.fr\/wp-content\/uploads\/2020\/03\/qualitetourisme-1.png 500w, https:\/\/www.chateaunantes.fr\/wp-content\/uploads\/2020\/03\/qualitetourisme-1-300x300.png 300w, https:\/\/www.chateaunantes.fr\/wp-content\/uploads\/2020\/03\/qualitetourisme-1-150x150.png 150w, https:\/\/www.chateaunantes.fr\/wp-content\/uploads\/2020\/03\/qualitetourisme-1-100x100.png 100w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<h3 class=\"wp-block-heading\" class=\"wp-block-heading\" id=\"qualite-tourisme\">Qualit\u00e9 tourisme<\/h3>\n\n\n\n<p>Comprometido desde el 2008 con una pol\u00edtica destinada a reforzar el nivel de atenci\u00f3n y de servicios, en colaboraci\u00f3n con Loire Atlantique d\u00e9veloppement, el Castillo de los Duques de Breta\u00f1a ha renovado la marca en 2021.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"477\" src=\"https:\/\/www.chateaunantes.fr\/wp-content\/uploads\/2020\/03\/tourismeethandicap-1.png\" alt=\"Logo Tourisme &amp; handicap\" class=\"wp-image-348 size-full\" srcset=\"https:\/\/www.chateaunantes.fr\/wp-content\/uploads\/2020\/03\/tourismeethandicap-1.png 500w, https:\/\/www.chateaunantes.fr\/wp-content\/uploads\/2020\/03\/tourismeethandicap-1-300x286.png 300w, https:\/\/www.chateaunantes.fr\/wp-content\/uploads\/2020\/03\/tourismeethandicap-1-100x95.png 100w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<h3 class=\"wp-block-heading\" class=\"wp-block-heading\" id=\"label-tourisme-handicap\">Label Tourisme &amp; Handicap<\/h3>\n\n\n\n<p>En 2023, el Castillo obtuvo el sello Tourisme &amp; Handicap por su adaptaci\u00f3n a los cuatro tipos de discapacidad (motriz, visual, auditiva, mental). Figura en la gu\u00eda \u00abBuenos usos y pr\u00e1cticas en materia de accesibilidad\u00bb.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"198\" src=\"https:\/\/www.chateaunantes.fr\/wp-content\/uploads\/2020\/03\/loireavelo.png\" alt=\"Logo Loire \u00e0 v\u00e9lo\" class=\"wp-image-320 size-full\" srcset=\"https:\/\/www.chateaunantes.fr\/wp-content\/uploads\/2020\/03\/loireavelo.png 500w, https:\/\/www.chateaunantes.fr\/wp-content\/uploads\/2020\/03\/loireavelo-300x119.png 300w, https:\/\/www.chateaunantes.fr\/wp-content\/uploads\/2020\/03\/loireavelo-100x40.png 100w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<h3 class=\"wp-block-heading\" class=\"wp-block-heading\" id=\"la-loire-a-velo\">La Loire \u00e0 v\u00e9lo<\/h3>\n\n\n\n<p>El castillo cuenta con el sello \u00abLa Loire \u00e0 V\u00e9lo\u00bb (El Loira en Bici),&nbsp;ruta ciclotur\u00edstica de 800 kil\u00f3metros de largo, \u00fanica en Francia. Habilitada en ambos sentidos, conecta Cuffy (a la altura de Nevers) con Saint-Brevin-les-Pins (frente a Saint-Nazaire) y atraviesa la ciudad de Nantes, permitiendo descubrir su patrimonio. <\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"760\" src=\"https:\/\/www.chateaunantes.fr\/wp-content\/uploads\/2020\/03\/accueilvelo.png\" alt=\"Logo accueil v\u00e9lo\" class=\"wp-image-323 size-full\" srcset=\"https:\/\/www.chateaunantes.fr\/wp-content\/uploads\/2020\/03\/accueilvelo.png 500w, https:\/\/www.chateaunantes.fr\/wp-content\/uploads\/2020\/03\/accueilvelo-197x300.png 197w, https:\/\/www.chateaunantes.fr\/wp-content\/uploads\/2020\/03\/accueilvelo-66x100.png 66w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<h3 class=\"wp-block-heading\" class=\"wp-block-heading\" id=\"accueil-velo\">Accueil v\u00e9lo<\/h3>\n\n\n\n<p>El castillo cuenta con el sello \u00abLa Loire \u00e0 V\u00e9lo\u00bb (El Loira en Bici),&nbsp;ruta ciclotur\u00edstica de 800 kil\u00f3metros de largo, \u00fanica en Francia. Habilitada en ambos sentidos, conecta Cuffy (a la altura de Nevers) con Saint-Brevin-les-Pins (frente a Saint-Nazaire) y atraviesa la ciudad de Nantes, permitiendo descubrir su patrimonio.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/www.chateaunantes.fr\/wp-content\/uploads\/2020\/03\/monumenthistorique.png\" alt=\"Logo monument historique\" class=\"wp-image-326 size-full\" srcset=\"https:\/\/www.chateaunantes.fr\/wp-content\/uploads\/2020\/03\/monumenthistorique.png 500w, https:\/\/www.chateaunantes.fr\/wp-content\/uploads\/2020\/03\/monumenthistorique-300x300.png 300w, https:\/\/www.chateaunantes.fr\/wp-content\/uploads\/2020\/03\/monumenthistorique-150x150.png 150w, https:\/\/www.chateaunantes.fr\/wp-content\/uploads\/2020\/03\/monumenthistorique-100x100.png 100w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<h3 class=\"wp-block-heading\" class=\"wp-block-heading\" id=\"monument-historique\">Monument historique<\/h3>\n\n\n\n<p>El Castillo fue declarado&nbsp;<em>Monumento hist\u00f3rico<\/em>&nbsp;en 1862.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/www.chateaunantes.fr\/wp-content\/uploads\/2020\/03\/Musee-de-France.png\" alt=\"Logo mus\u00e9e de France\" class=\"wp-image-352 size-full\" srcset=\"https:\/\/www.chateaunantes.fr\/wp-content\/uploads\/2020\/03\/Musee-de-France.png 500w, https:\/\/www.chateaunantes.fr\/wp-content\/uploads\/2020\/03\/Musee-de-France-300x300.png 300w, https:\/\/www.chateaunantes.fr\/wp-content\/uploads\/2020\/03\/Musee-de-France-150x150.png 150w, https:\/\/www.chateaunantes.fr\/wp-content\/uploads\/2020\/03\/Musee-de-France-100x100.png 100w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<h3 class=\"wp-block-heading\" class=\"wp-block-heading\" id=\"musee-de-france\">Mus\u00e9e de France<\/h3>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"372\" src=\"https:\/\/www.chateaunantes.fr\/wp-content\/uploads\/2020\/03\/chateauxdelaloire.png\" alt=\"Logo chateaux de la Loire\" class=\"wp-image-332 size-full\" srcset=\"https:\/\/www.chateaunantes.fr\/wp-content\/uploads\/2020\/03\/chateauxdelaloire.png 500w, https:\/\/www.chateaunantes.fr\/wp-content\/uploads\/2020\/03\/chateauxdelaloire-300x223.png 300w, https:\/\/www.chateaunantes.fr\/wp-content\/uploads\/2020\/03\/chateauxdelaloire-100x74.png 100w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<h3 class=\"wp-block-heading\" class=\"wp-block-heading\" id=\"castillos-del-loira\">Castillos del Loira&nbsp;<\/h3>\n\n\n\n<p>L\u2019association \u00ab Ch\u00e2teaux de la Loire, Vall\u00e9e des Rois \u00bb a \u00e9La asociaci\u00f3n \u00abCh\u00e2teaux de la Loire, Vall\u00e9e des Rois\u00bb fue creada en 2008 con el prop\u00f3sito de agrupar cincuenta monumentos a lo largo del r\u00edo Loira desde Nantes (44) hasta Briare (45). <\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"189\" src=\"https:\/\/www.chateaunantes.fr\/wp-content\/uploads\/2020\/03\/loire-atlantique-developpement.png\" alt=\"Logo loire atlantique d\u00e9veloppement\" class=\"wp-image-335 size-full\" srcset=\"https:\/\/www.chateaunantes.fr\/wp-content\/uploads\/2020\/03\/loire-atlantique-developpement.png 500w, https:\/\/www.chateaunantes.fr\/wp-content\/uploads\/2020\/03\/loire-atlantique-developpement-300x113.png 300w, https:\/\/www.chateaunantes.fr\/wp-content\/uploads\/2020\/03\/loire-atlantique-developpement-100x38.png 100w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<h3 class=\"wp-block-heading\" class=\"wp-block-heading\" id=\"loire-atlantique-developpement\">Loire-Atlantique d\u00e9veloppement<\/h3>\n\n\n\n<p>La acci\u00f3n tur\u00edstica de Loire-Atlantique d\u00e9veloppement acompa\u00f1a al Castillo de los Duques de Breta\u00f1a en el procedimiento de obtenci\u00f3n de la marca Qualit\u00e9 Tourisme.<br>Loire-Atlantique d\u00e9veloppement tiene como misi\u00f3n colaborar en la promoci\u00f3n del departamento de Loire-Atlantique y acompa\u00f1ar a los profesionales en el desarrollo de su oferta tur\u00edstica.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"757\" src=\"https:\/\/www.chateaunantes.fr\/wp-content\/uploads\/2020\/03\/mom_art.png\" alt=\"Logo Mom'art\" class=\"wp-image-338 size-full\" srcset=\"https:\/\/www.chateaunantes.fr\/wp-content\/uploads\/2020\/03\/mom_art.png 500w, https:\/\/www.chateaunantes.fr\/wp-content\/uploads\/2020\/03\/mom_art-198x300.png 198w, https:\/\/www.chateaunantes.fr\/wp-content\/uploads\/2020\/03\/mom_art-66x100.png 66w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<h3 class=\"wp-block-heading\" class=\"wp-block-heading\" id=\"momart\">Mom\u2019Art<\/h3>\n\n\n\n<p>La carta M\u00f4m\u2019Art ha sido redactada por padres y visitantes deseosos de acompa\u00f1ar a los ni\u00f1os en el museo. El castillo se compromete a hacer todo lo posible por brindar la mejor atenci\u00f3n a ni\u00f1os y familias.<\/p>\n\n\n\n<p>El museo se ha adherido a los&nbsp;<a href=\"https:\/\/mom-art.org\/les-dix-droits-du-petit-visiteur\/\" target=\"_blank\" aria-label=\"undefined (s\u2019ouvre dans un nouvel onglet)\" rel=\"noreferrer noopener\">\u201cdiez derechos de los peque\u00f1os visitantes\u201d<\/a>.&nbsp;<\/p>\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>La atenci\u00f3n al p\u00fablico es primordial en el proyecto del castillo, comprometido con procedimientos de calidad y obtenci\u00f3n de certificaciones. Qualit\u00e9 tourisme Comprometido desde el 2008 con una pol\u00edtica destinada a reforzar el nivel de atenci\u00f3n y de servicios, en colaboraci\u00f3n con Loire Atlantique d\u00e9veloppement, el Castillo de los Duques de Breta\u00f1a ha renovado la [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":312,"parent":7918,"menu_order":203,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"indications-recherche":[],"class_list":["post-7926","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Socios y etiquetas del Castillo de los Duques de Breta\u00f1a<\/title>\n<meta name=\"description\" content=\"La atenci\u00f3n al p\u00fablico es primordial en el proyecto del castillo, comprometido con procedimientos de calidad y obtenci\u00f3n de certificaciones.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.chateaunantes.fr\/es\/el-castillo\/sellos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Socios y etiquetas del Castillo de los Duques de Breta\u00f1a\" \/>\n<meta property=\"og:description\" content=\"La atenci\u00f3n al p\u00fablico es primordial en el proyecto del castillo, comprometido con procedimientos de calidad y obtenci\u00f3n de certificaciones.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.chateaunantes.fr\/es\/el-castillo\/sellos\/\" \/>\n<meta property=\"og:site_name\" content=\"Ch\u00e2teau des ducs de Bretagne | Mus\u00e9e d\u2019histoire de Nantes\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/fr-fr.facebook.com\/chateaunantes\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-08T10:34:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.chateaunantes.fr\/wp-content\/uploads\/2020\/03\/chateau_banner.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2345\" \/>\n\t<meta property=\"og:image:height\" content=\"1630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.chateaunantes.fr\/es\/el-castillo\/sellos\/\",\"url\":\"https:\/\/www.chateaunantes.fr\/es\/el-castillo\/sellos\/\",\"name\":\"Socios y etiquetas del Castillo de los Duques de Breta\u00f1a\",\"isPartOf\":{\"@id\":\"https:\/\/www.chateaunantes.fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.chateaunantes.fr\/es\/el-castillo\/sellos\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.chateaunantes.fr\/es\/el-castillo\/sellos\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.chateaunantes.fr\/wp-content\/uploads\/2020\/03\/chateau_banner.jpg\",\"datePublished\":\"2021-01-18T15:40:19+00:00\",\"dateModified\":\"2026-07-08T10:34:33+00:00\",\"description\":\"La atenci\u00f3n al p\u00fablico es primordial en el proyecto del castillo, comprometido con procedimientos de calidad y obtenci\u00f3n de certificaciones.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.chateaunantes.fr\/es\/el-castillo\/sellos\/#breadcrumb\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.chateaunantes.fr\/es\/el-castillo\/sellos\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\/\/www.chateaunantes.fr\/es\/el-castillo\/sellos\/#primaryimage\",\"url\":\"https:\/\/www.chateaunantes.fr\/wp-content\/uploads\/2020\/03\/chateau_banner.jpg\",\"contentUrl\":\"https:\/\/www.chateaunantes.fr\/wp-content\/uploads\/2020\/03\/chateau_banner.jpg\",\"width\":2345,\"height\":1630,\"caption\":\"Ch\u00e2teau des ducs de Bretagne \u2013 \u00a9 Franck Tomps \/ LVAN\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.chateaunantes.fr\/es\/el-castillo\/sellos\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.chateaunantes.fr\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El castillo\",\"item\":\"https:\/\/www.chateaunantes.fr\/es\/el-castillo\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Sellos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.chateaunantes.fr\/#website\",\"url\":\"https:\/\/www.chateaunantes.fr\/\",\"name\":\"Ch\u00e2teau des ducs de Bretagne | Mus\u00e9e d\u2019histoire de Nantes\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.chateaunantes.fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.chateaunantes.fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.chateaunantes.fr\/#organization\",\"name\":\"Ch\u00e2teau des ducs de Bretagne | Mus\u00e9e d\u2019histoire de Nantes\",\"url\":\"https:\/\/www.chateaunantes.fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\/\/www.chateaunantes.fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.chateaunantes.fr\/wp-content\/uploads\/2024\/09\/logo_noir.svg\",\"contentUrl\":\"https:\/\/www.chateaunantes.fr\/wp-content\/uploads\/2024\/09\/logo_noir.svg\",\"width\":1,\"height\":1,\"caption\":\"Ch\u00e2teau des ducs de Bretagne | Mus\u00e9e d\u2019histoire de Nantes\"},\"image\":{\"@id\":\"https:\/\/www.chateaunantes.fr\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/fr-fr.facebook.com\/chateaunantes\",\"https:\/\/www.instagram.com\/chateaunantes\/\",\"https:\/\/www.linkedin.com\/company\/chteau-des-ducs-de-bretagne\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Socios y etiquetas del Castillo de los Duques de Breta\u00f1a","description":"La atenci\u00f3n al p\u00fablico es primordial en el proyecto del castillo, comprometido con procedimientos de calidad y obtenci\u00f3n de certificaciones.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.chateaunantes.fr\/es\/el-castillo\/sellos\/","og_locale":"es_ES","og_type":"article","og_title":"Socios y etiquetas del Castillo de los Duques de Breta\u00f1a","og_description":"La atenci\u00f3n al p\u00fablico es primordial en el proyecto del castillo, comprometido con procedimientos de calidad y obtenci\u00f3n de certificaciones.","og_url":"https:\/\/www.chateaunantes.fr\/es\/el-castillo\/sellos\/","og_site_name":"Ch\u00e2teau des ducs de Bretagne | Mus\u00e9e d\u2019histoire de Nantes","article_publisher":"https:\/\/fr-fr.facebook.com\/chateaunantes","article_modified_time":"2026-07-08T10:34:33+00:00","og_image":[{"width":2345,"height":1630,"url":"https:\/\/www.chateaunantes.fr\/wp-content\/uploads\/2020\/03\/chateau_banner.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.chateaunantes.fr\/es\/el-castillo\/sellos\/","url":"https:\/\/www.chateaunantes.fr\/es\/el-castillo\/sellos\/","name":"Socios y etiquetas del Castillo de los Duques de Breta\u00f1a","isPartOf":{"@id":"https:\/\/www.chateaunantes.fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.chateaunantes.fr\/es\/el-castillo\/sellos\/#primaryimage"},"image":{"@id":"https:\/\/www.chateaunantes.fr\/es\/el-castillo\/sellos\/#primaryimage"},"thumbnailUrl":"https:\/\/www.chateaunantes.fr\/wp-content\/uploads\/2020\/03\/chateau_banner.jpg","datePublished":"2021-01-18T15:40:19+00:00","dateModified":"2026-07-08T10:34:33+00:00","description":"La atenci\u00f3n al p\u00fablico es primordial en el proyecto del castillo, comprometido con procedimientos de calidad y obtenci\u00f3n de certificaciones.","breadcrumb":{"@id":"https:\/\/www.chateaunantes.fr\/es\/el-castillo\/sellos\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.chateaunantes.fr\/es\/el-castillo\/sellos\/"]}]},{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/www.chateaunantes.fr\/es\/el-castillo\/sellos\/#primaryimage","url":"https:\/\/www.chateaunantes.fr\/wp-content\/uploads\/2020\/03\/chateau_banner.jpg","contentUrl":"https:\/\/www.chateaunantes.fr\/wp-content\/uploads\/2020\/03\/chateau_banner.jpg","width":2345,"height":1630,"caption":"Ch\u00e2teau des ducs de Bretagne \u2013 \u00a9 Franck Tomps \/ LVAN"},{"@type":"BreadcrumbList","@id":"https:\/\/www.chateaunantes.fr\/es\/el-castillo\/sellos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.chateaunantes.fr\/es\/"},{"@type":"ListItem","position":2,"name":"El castillo","item":"https:\/\/www.chateaunantes.fr\/es\/el-castillo\/"},{"@type":"ListItem","position":3,"name":"Sellos"}]},{"@type":"WebSite","@id":"https:\/\/www.chateaunantes.fr\/#website","url":"https:\/\/www.chateaunantes.fr\/","name":"Ch\u00e2teau des ducs de Bretagne | Mus\u00e9e d\u2019histoire de Nantes","description":"","publisher":{"@id":"https:\/\/www.chateaunantes.fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.chateaunantes.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"},{"@type":"Organization","@id":"https:\/\/www.chateaunantes.fr\/#organization","name":"Ch\u00e2teau des ducs de Bretagne | Mus\u00e9e d\u2019histoire de Nantes","url":"https:\/\/www.chateaunantes.fr\/","logo":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/www.chateaunantes.fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.chateaunantes.fr\/wp-content\/uploads\/2024\/09\/logo_noir.svg","contentUrl":"https:\/\/www.chateaunantes.fr\/wp-content\/uploads\/2024\/09\/logo_noir.svg","width":1,"height":1,"caption":"Ch\u00e2teau des ducs de Bretagne | Mus\u00e9e d\u2019histoire de Nantes"},"image":{"@id":"https:\/\/www.chateaunantes.fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/fr-fr.facebook.com\/chateaunantes","https:\/\/www.instagram.com\/chateaunantes\/","https:\/\/www.linkedin.com\/company\/chteau-des-ducs-de-bretagne"]}]}},"_links":{"self":[{"href":"https:\/\/www.chateaunantes.fr\/es\/wp-json\/wp\/v2\/pages\/7926"}],"collection":[{"href":"https:\/\/www.chateaunantes.fr\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.chateaunantes.fr\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.chateaunantes.fr\/es\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/www.chateaunantes.fr\/es\/wp-json\/wp\/v2\/comments?post=7926"}],"version-history":[{"count":2,"href":"https:\/\/www.chateaunantes.fr\/es\/wp-json\/wp\/v2\/pages\/7926\/revisions"}],"predecessor-version":[{"id":19516,"href":"https:\/\/www.chateaunantes.fr\/es\/wp-json\/wp\/v2\/pages\/7926\/revisions\/19516"}],"up":[{"embeddable":true,"href":"https:\/\/www.chateaunantes.fr\/es\/wp-json\/wp\/v2\/pages\/7918"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.chateaunantes.fr\/es\/wp-json\/wp\/v2\/media\/312"}],"wp:attachment":[{"href":"https:\/\/www.chateaunantes.fr\/es\/wp-json\/wp\/v2\/media?parent=7926"}],"wp:term":[{"taxonomy":"indications-recherche","embeddable":true,"href":"https:\/\/www.chateaunantes.fr\/es\/wp-json\/wp\/v2\/indications-recherche?post=7926"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}